{"id":44,"date":"2018-01-19T13:36:15","date_gmt":"2018-01-19T12:36:15","guid":{"rendered":"http:\/\/www.anteltecno.eu\/atp\/?page_id=44"},"modified":"2019-03-22T18:11:18","modified_gmt":"2019-03-22T17:11:18","slug":"avicoltura","status":"publish","type":"page","link":"https:\/\/www.anteltecno.eu\/index.php\/avicoltura\/","title":{"rendered":"Elettronica per Avicoltura Incubatrice\/Schiusa\/Contapulcini"},"content":{"rendered":"\n<ul class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/Incubatrice1-300x169.jpg\" alt=\"\" data-id=\"199\" class=\"wp-image-199\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/Incubatrice1-300x169.jpg 300w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/Incubatrice1-768x433.jpg 768w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/Incubatrice1-528x297.jpg 528w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/Incubatrice1.jpg 852w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"188\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/pulcini-e1517051240743-300x188.jpg\" alt=\"\" data-id=\"60\" class=\"wp-image-60\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/pulcini-e1517051240743-300x188.jpg 300w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/pulcini-e1517051240743.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1349\" height=\"602\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/Banner_1.jpg\" alt=\"\" class=\"wp-image-344\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/Banner_1.jpg 1349w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/Banner_1-300x134.jpg 300w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/Banner_1-768x343.jpg 768w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/Banner_1-1024x457.jpg 1024w\" sizes=\"auto, (max-width: 1349px) 100vw, 1349px\" \/><\/figure><\/div>\n\n\n\n<p>Per il settore dell\u2019avicoltura professionale ANTEL TECNO realizza molteplici tipologie di <strong>centraline elettroniche<\/strong> di controllo a microprocessore&nbsp; per <strong>Incubatrici, Schiuse, Contapulcini, Allevamento<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Le centraline hanno il delicato compito di regolare e mantenere i parametri per la nascita, lo sviluppo e la vita del pulcino.<\/p>\n\n\n\n<p>Tra i pi\u00f9 importanti ci sono:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> Temperatura <\/li><li> Umidit\u00e0 <\/li><li> Ventilazione <\/li><li> Aspirazione <\/li><li> Girauova <\/li><li> ecc&#8230;. <\/li><\/ul>\n\n\n\n<p>Ogni centralina pu\u00f2 lavorare sia in locale,<strong>&nbsp;in piena autonomia<\/strong>,\n sia in collegamento con il server di gestione e controllo e, a seconda \ndel modello, \u00e8 possibile controllare e gestire da 1 a&nbsp;8 zone climatiche.<\/p>\n\n\n\n<p>Tutte le centraline sono dotate di&nbsp;<strong>display LCD<\/strong>&nbsp;con ottima leggibilit\u00e0 (di dimensioni elevate nel modello ATXP8) e di<strong>&nbsp;LED segnalatori<\/strong>&nbsp;per\n garantire un chiaro ed immediato quadro dello stato della macchina \n(processi in corso, allarmi, comunicazioni con il server ecc&#8230;).<\/p>\n\n\n\n<p>Grazie ai sofisticati algoritmi per il controllo della temperatura, \nle centraline permettono un basso consumo energetico dell&#8217;impianto.<\/p>\n\n\n\n<p>La ATXP8 dispone di diversi ingressi ed uscite supplementari per eventuali funzioni aggiuntive.<\/p>\n\n\n\n<p>Per gli allevamenti, la base della centralina \u00e8 la stessa, ma \u00e8 presente un software specifico.<\/p>\n\n\n\n<p>Tutte le centraline prodotte da ANTEL TECNO sono personalizzabili per soddisfare pienamente le esigenze dell&#8217;utilizzatore.<\/p>\n\n\n\n<p>Ogni centralina pu\u00f2 lavorare sia in locale,<strong>&nbsp;in piena autonomia<\/strong>,\n sia in collegamento con il server di gestione e controllo e, a seconda \ndel modello, \u00e8 possibile controllare e gestire da 1 a&nbsp;8 zone climatiche.<\/p>\n\n\n\n<p>Tutte le centraline sono dotate di&nbsp;<strong>display LCD<\/strong>&nbsp;con ottima leggibilit\u00e0 (di dimensioni elevate nel modello ATXP8) e di<strong>&nbsp;LED segnalatori<\/strong>&nbsp;per\n garantire un chiaro ed immediato quadro dello stato della macchina \n(processi in corso, allarmi, comunicazioni con il server ecc&#8230;).<\/p>\n\n\n\n<p>Grazie ai sofisticati algoritmi per il controllo della temperatura, \nle centraline permettono un basso consumo energetico dell&#8217;impianto.<\/p>\n\n\n\n<p>La ATXP8 dispone di diversi ingressi ed uscite supplementari per eventuali funzioni aggiuntive.<\/p>\n\n\n\n<p>Per gli allevamenti, la base della centralina \u00e8 la stessa, ma \u00e8 presente un software specifico.<\/p>\n\n\n\n<p>Tutte le centraline prodotte da ANTEL TECNO sono personalizzabili per soddisfare pienamente le esigenze dell&#8217;utilizzatore.<\/p>\n\n\n\n<p>__________________________________<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:33% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"692\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/ATXP8_Sito-1024x692.jpg\" alt=\"\" class=\"wp-image-380\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/ATXP8_Sito-1024x692.jpg 1024w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/ATXP8_Sito-300x203.jpg 300w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/ATXP8_Sito-768x519.jpg 768w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2019\/03\/ATXP8_Sito.jpg 1246w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-background has-very-light-gray-background-color\"><a href=\"https:\/\/www.anteltecno.eu\/index.php\/atxp8\/\">CENTRALINA ATXP8 &#8211; CONTROLLO COMPLETO FINO A 8 ZONE PER\u00a0 INCUBATRICI E SCHIUSE<\/a><\/p>\n\n\n\n<p>\nCodice: ATXP8\n\n<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:33% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"192\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg\" alt=\"\" class=\"wp-image-78\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg 191w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A-150x150.jpg 150w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-background has-very-light-gray-background-color\"><a href=\"https:\/\/anteltecno.eu\/index.php\/atxp9\/\">INTERFACCIA ATXP9<\/a><\/p>\n\n\n\n<p>\n Codice: ATXP9 \n\n<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"192\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg\" alt=\"\" class=\"wp-image-78\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg 191w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A-150x150.jpg 150w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-background has-very-light-gray-background-color\"><a href=\"https:\/\/www.anteltecno.eu\/index.php\/sonda-sensore-attivo-temperatura-tp1\/\">SONDA SENSORE ATTIVO TEMPERATURA TP1<\/a> <\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Codice: TP1 \u00a0  <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:33% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"192\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg\" alt=\"\" class=\"wp-image-78\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg 191w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A-150x150.jpg 150w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-background has-very-light-gray-background-color\"><a href=\"https:\/\/www.anteltecno.eu\/index.php\/sonda-sensore-attivo-umidita-um1\/\">SONDA SENSORE ATTIVO UMIDITA&#8217; UM1<\/a> <\/p>\n\n\n\n<p>Codice: UM1 \u00a0  <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"192\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg\" alt=\"\" class=\"wp-image-78\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg 191w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A-150x150.jpg 150w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-background has-very-light-gray-background-color\"><a href=\"https:\/\/www.anteltecno.eu\/index.php\/estensore-zona-extp8\/\">ESTENSORE DI ZONA PER ATXP8<\/a> <\/p>\n\n\n\n<p>Codice: EXTP8 <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"192\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg\" alt=\"\" class=\"wp-image-78\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg 191w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A-150x150.jpg 150w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-background has-very-light-gray-background-color\"><a href=\"https:\/\/www.anteltecno.eu\/at\/Prodotti\/MULTIALLARME-DI-SICUREZZA-PER-CONTROLLO-DI-SOVRASOTTO-TEMPERATURA\/51-22.htm\">MULTIALLARME DI SICUREZZA PER CONTROLLO DI SOVRA\/SOTTO TEMPERATURA<\/a> <\/p>\n\n\n\n<p>Codice: ATWD2 <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"192\" src=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg\" alt=\"\" class=\"wp-image-78\" srcset=\"https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A.jpg 191w, https:\/\/www.anteltecno.eu\/atp\/wp-content\/uploads\/2018\/01\/AT_02A-150x150.jpg 150w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-background has-very-light-gray-background-color\"><a href=\"https:\/\/www.anteltecno.eu\/index.php\/contapulcini\/\">TESTATE CONTAPULCINI<\/a> <\/p>\n\n\n\n<p>Codice: ATTCVAR \u00a0 <\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Per il settore dell\u2019avicoltura professionale ANTEL TECNO realizza molteplici tipologie di centraline elettroniche di controllo a microprocessore&nbsp; per Incubatrici, Schiuse, Contapulcini, Allevamento.&nbsp;&nbsp; Le centraline hanno il delicato compito di regolare e mantenere i parametri per la nascita, lo sviluppo e la vita del pulcino. Tra i pi\u00f9 importanti ci sono: Temperatura Umidit\u00e0 Ventilazione Aspirazione Girauova [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-44","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.anteltecno.eu\/index.php\/wp-json\/wp\/v2\/pages\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anteltecno.eu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.anteltecno.eu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.anteltecno.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anteltecno.eu\/index.php\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":113,"href":"https:\/\/www.anteltecno.eu\/index.php\/wp-json\/wp\/v2\/pages\/44\/revisions"}],"predecessor-version":[{"id":417,"href":"https:\/\/www.anteltecno.eu\/index.php\/wp-json\/wp\/v2\/pages\/44\/revisions\/417"}],"wp:attachment":[{"href":"https:\/\/www.anteltecno.eu\/index.php\/wp-json\/wp\/v2\/media?parent=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}